{"id":29,"count":9,"description":"","link":"https:\/\/dev.sa.ro.it\/en\/settori\/impianti-di-riciclo\/","name":"Impianti di riciclo","slug":"impianti-di-riciclo","taxonomy":"settori-cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impianti di riciclo Archives - Wear Protection | Saro<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impianti di riciclo Archives - Wear Protection | Saro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.sa.ro.it\/en\/settori\/impianti-di-riciclo\/\" \/>\n<meta property=\"og:site_name\" content=\"Wear Protection | Saro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/dev.sa.ro.it\\\/settori\\\/impianti-di-riciclo\\\/\",\"url\":\"https:\\\/\\\/dev.sa.ro.it\\\/settori\\\/impianti-di-riciclo\\\/\",\"name\":\"Impianti di riciclo Archives - Wear Protection | Saro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dev.sa.ro.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dev.sa.ro.it\\\/settori\\\/impianti-di-riciclo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dev.sa.ro.it\\\/settori\\\/impianti-di-riciclo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dev.sa.ro.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impianti di riciclo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dev.sa.ro.it\\\/#website\",\"url\":\"https:\\\/\\\/dev.sa.ro.it\\\/\",\"name\":\"Wear Protection | Saro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dev.sa.ro.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dev.sa.ro.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dev.sa.ro.it\\\/#organization\",\"name\":\"Wear Protection | Saro\",\"url\":\"https:\\\/\\\/dev.sa.ro.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dev.sa.ro.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dev.sa.ro.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-black.svg\",\"contentUrl\":\"https:\\\/\\\/dev.sa.ro.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-black.svg\",\"caption\":\"Wear Protection | Saro\"},\"image\":{\"@id\":\"https:\\\/\\\/dev.sa.ro.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/saro-wear-protection\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impianti di riciclo Archives - Wear Protection | Saro","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Impianti di riciclo Archives - Wear Protection | Saro","og_url":"https:\/\/dev.sa.ro.it\/en\/settori\/impianti-di-riciclo\/","og_site_name":"Wear Protection | Saro","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dev.sa.ro.it\/settori\/impianti-di-riciclo\/","url":"https:\/\/dev.sa.ro.it\/settori\/impianti-di-riciclo\/","name":"Impianti di riciclo Archives - Wear Protection | Saro","isPartOf":{"@id":"https:\/\/dev.sa.ro.it\/#website"},"breadcrumb":{"@id":"https:\/\/dev.sa.ro.it\/settori\/impianti-di-riciclo\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.sa.ro.it\/settori\/impianti-di-riciclo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.sa.ro.it\/"},{"@type":"ListItem","position":2,"name":"Impianti di riciclo"}]},{"@type":"WebSite","@id":"https:\/\/dev.sa.ro.it\/#website","url":"https:\/\/dev.sa.ro.it\/","name":"Wear Protection | Saro","description":"","publisher":{"@id":"https:\/\/dev.sa.ro.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.sa.ro.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dev.sa.ro.it\/#organization","name":"Wear Protection | Saro","url":"https:\/\/dev.sa.ro.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.sa.ro.it\/#\/schema\/logo\/image\/","url":"https:\/\/dev.sa.ro.it\/wp-content\/uploads\/2026\/03\/logo-black.svg","contentUrl":"https:\/\/dev.sa.ro.it\/wp-content\/uploads\/2026\/03\/logo-black.svg","caption":"Wear Protection | Saro"},"image":{"@id":"https:\/\/dev.sa.ro.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/saro-wear-protection\/"]}]}},"_links":{"self":[{"href":"https:\/\/dev.sa.ro.it\/en\/wp-json\/wp\/v2\/settori-cat\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.sa.ro.it\/en\/wp-json\/wp\/v2\/settori-cat"}],"about":[{"href":"https:\/\/dev.sa.ro.it\/en\/wp-json\/wp\/v2\/taxonomies\/settori-cat"}],"wp:post_type":[{"href":"https:\/\/dev.sa.ro.it\/en\/wp-json\/wp\/v2\/prodotti?settori-cat=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}